{"id":1897,"date":"2024-07-02T10:56:00","date_gmt":"2024-07-02T10:56:00","guid":{"rendered":"https:\/\/www.bhoost.com\/it\/?p=1897"},"modified":"2024-07-31T12:22:15","modified_gmt":"2024-07-31T12:22:15","slug":"il-potere-dell-e-commerce-componibile-senza-stress-con-shopware","status":"publish","type":"post","link":"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/","title":{"rendered":"Il potere dell&#8217; E-Commerce componibile senza stress con Shopware"},"content":{"rendered":"\n<p>Immagina di abbandonare i limiti di un negozio online tradizionale e di creare esperienze di acquisto uniche che catturino i tuoi clienti. Con <a href=\"https:\/\/www.shopware.com\/en\/\">Shopware<\/a>, una piattaforma di e-commerce a prova di futuro, puoi! Shopware ti consente di abbracciare il <strong>commercio headless e componibile<\/strong>, ossia un approccio rivoluzionario che abbatte le barriere e fa volare la tua creativit\u00e0. Curioso? Allora preparati a scoprire un mondo di possibilit\u00e0 con Shopware!<\/p>\n\n\n\n<p>(E ehi, mentre esploriamo, ricorda che Bhoost offre s<a href=\"https:\/\/www.bhoost.com\/it\/vps-shopware-cloud\/\">ervizi hosting Shopware<\/a> ottimizzati, perfetti per mantenere il tuo E-Commerce efficiente e con super prestazioni!)<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04a6a046a6a\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04a6a046a6a\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/#A_proposito_di_Shopware\" >A proposito di Shopware<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/#Cose_lheadless_commerce\" >Cos\u2019\u00e8 l&#8217;headless commerce?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/#Vantaggi_del_commercio_senza_testa\" >Vantaggi del commercio senza testa<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/#Shopware_e_commercio_componibile_il_futuro_della_flessibilita\" >Shopware e commercio componibile: il futuro della flessibilit\u00e0<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/#Vantaggi_del_commercio_componibile_con_Shopware\" >Vantaggi del commercio componibile con Shopware<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/il-potere-dell-e-commerce-componibile-senza-stress-con-shopware\/#Pronto_a_sfruttare_la_potenza_di_Shopware\" >Pronto a sfruttare la potenza di Shopware?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_proposito_di_Shopware\"><\/span><strong>A proposito di Shopware<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><a href=\"https:\/\/www.bhoost.com\/it\/piattaforme-ecommerce\/cosa-e-shopware-e-perche-e-cosi-popolare-per-l-ecommerce\/\">Shopware<\/a> \u00e8 una stella nascente nel <strong>e-commerce<\/strong> mondo, ideale per aziende ambiziose che cercano di espandersi. Questa <strong>piattaforma sofisticata<\/strong> \u00e8 progettato per i commercianti medio-piccoli, con la capacit\u00e0 di gestire modelli B2C, D2C, B2B. <\/p>\n\n\n\n<p>La magia di Shopware sta proprio in questa <strong>architettura open source basata sulle API<\/strong>, che ti garantisce flessibilit\u00e0 e controllo senza pari. Questo si traduce in una vetrina altamente personalizzabile su misura per il tuo marchio, che va incontro anche alle esigenze dei clienti. Inoltre, con oltre 34.000 fiorenti negozi online gi\u00e0 gestiti da Shopware, entrerai a far parte di una community di e-commerce.<\/p>\n\n\n\n<p>E la parte migliore? Shopware \u00e8 perfetto per l&#8217; headless commerce, il che significa che puoi liberarti dai limiti tradizionali e creare esperienze di acquisto rivoluzionarie che stupiranno i tuoi clienti. Esploriamo come l&#8217;approccio headless di Shopware pu\u00f2 potenziare la tua attivit\u00e0!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cose_lheadless_commerce\"><\/span><strong>Cos\u2019\u00e8 l&#8217;headless commerce?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>In sostanza, si tratta di una piattaforma tecnologica E-Commerce<strong> <\/strong>che separa il back-end (per la gestione dei prodotti e funzionalit\u00e0), dal front-end (ossia la parte visibile agli utenti) con le pagine di prodotto, e gli altri elementi.<\/p>\n\n\n\n<p>Consideralo come una rivoluzione della struttura tradizionale del negozio, in cui il frontend (la vetrina visiva) opera indipendentemente dal backend (il motore che fa funzionare tutto). Ma non temere, rimangono connessi tramite una &#8220;piccola API intelligente&#8221;.<\/p>\n\n\n\n<p>Questo <strong>personalit\u00e0 divisa<\/strong> ti d\u00e0 un&#8217;incredibile flessibilit\u00e0. Puoi sperimentare nuovi design di frontend senza compromettere il buon funzionamento del tuo backend. Vuoi lanciare un&#8217;app mobile stravagante o integrare il tuo negozio in un chatbot? L&#8217;headless commerce lo rende un gioco da ragazzi! <\/p>\n\n\n\n<p>Questa agilit\u00e0 ti mantiene al passo con la curva in evoluzione dell&#8217;e-commerce, permettendoti di testare nuove tendenze e abbracciare tecnologie future come gli assistenti vocali o la realt\u00e0 aumentata. Fondamentalmente, l&#8217; headless commerce libera la tua immaginazione per creare esperienze di acquisto cos\u00ec straordinarie, che lasceranno i tuoi clienti dire: <strong>\u201cMolto bene!\u201d<\/strong><\/p>\n\n\n\n<p>Ora, tuffiamoci nei vantaggi tangibili derivanti dall&#8217;abbracciare questa rivoluzione headless!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Vantaggi_del_commercio_senza_testa\"><\/span><strong>Vantaggi del commercio senza testa<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Scatena l&#8217;anima <strong>innovatrice dell\u2019e-commerce<\/strong> con il potere dell&#8217; headless commerce! Ecco un assaggio di <strong>notevoli vantaggi<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sii un trendsetter, non un follower:<\/strong> Elimina le limitazioni dei modelli predefiniti. L&#8217; headless commerce ti consente di <strong>progettare una vetrina all&#8217;avanguardia<\/strong> che riflette il tuo marchio unico e ti mantiene al passo con i tempi. Nuova tendenza del design? Nessun problema! Aggiorna semplicemente il frontend senza influire sul backend.<\/li>\n\n\n\n<li><strong>Scala come un supereroe:<\/strong> Immaginare di <strong>gestire senza sforzo i picchi di traffico<\/strong> durante i saldi festivi o il lancio di nuovi prodotti. L&#8217; headless commerce ti consente di <strong>ridimensionare in modo indipendente il tuo frontend e il tuo backend<\/strong>, garantendo le massime prestazioni indipendentemente da quanto siano impegnative le cose.<\/li>\n\n\n\n<li><strong>Il contenuto \u00e8 re (o regina):<\/strong> Sono finiti i giorni dei goffi aggiornamenti dei contenuti. L&#8217; headless commerce ti consente di <strong>gestire i tuoi contenuti attraverso un sistema separato<\/strong> (come un <strong>CMS headless<\/strong>), permettendo <strong>modifiche pi\u00f9 veloci, pagine di prodotto personalizzate<\/strong>, e <strong>campagne di marketing mirate<\/strong> \u2013 il tutto senza toccare il backend principale.<\/li>\n\n\n\n<li><strong>Beatitudine omnicanale:<\/strong> Incontra i tuoi clienti <strong>ovunque facciano acquisti<\/strong>. L&#8217; headless commerce rende tutto pi\u00f9 semplice e <strong>integra il tuo negozio su pi\u00f9 canali<\/strong>: dalle app mobili, ai social media, agli assistenti vocali. Questa <strong>esperienza omnicanale senza soluzione di continuit\u00e0<\/strong> mantiene il tuo marchio in primo piano, indipendentemente dal dispositivo utilizzato.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Shopware_e_commercio_componibile_il_futuro_della_flessibilita\"><\/span><strong>Shopware e commercio componibile: il futuro della flessibilit\u00e0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Il commercio componibile fa fare un ulteriore passo avanti all&#8217; headless commerce, suddividendo l&#8217;ecosistema dell&#8217;e-commerce in componenti modulari. Ogni componente, come un sistema di gestione delle informazioni sul prodotto (PIM) o un sistema di gestione dei contenuti (CMS), pu\u00f2 essere una soluzione all&#8217;avanguardia, scelta e integrata perfettamente tramite API.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Vantaggi_del_commercio_componibile_con_Shopware\"><\/span><strong>Vantaggi del commercio componibile con Shopware<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Adottando il commercio componibile con Shopware, le aziende raggiungono un nuovo livello di flessibilit\u00e0 e di capacit\u00e0 di affrontare il futuro:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Flessibilit\u00e0 senza pari:<\/strong> Shopware ti consente di integrare i componenti software perfetti per le tue esigenze specifiche, creando una soluzione di e-commerce davvero personalizzata.<\/li>\n\n\n\n<li><strong>Scalabilit\u00e0 a prova di futuro:<\/strong> L&#8217;approccio componibile consente il ridimensionamento indipendente del frontend e del backend. Ci\u00f2 garantisce che il tuo negozio possa gestire i picchi di crescita senza sforzo, mantenendo il passo con le tue ambizioni.<\/li>\n\n\n\n<li><strong>Padronanza multicanale (migliorata):<\/strong> Il commercio componibile ti consente di offrire esperienze omnicanale senza soluzione di continuit\u00e0. Integra il tuo negozio con vari punti di contatto, dai social media alle app mobili, garantendo un&#8217;esperienza di brand coerente per i tuoi clienti, indipendentemente da dove effettuano gli acquisti.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pronto_a_sfruttare_la_potenza_di_Shopware\"><\/span><strong>Pronto a sfruttare la potenza di Shopware?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Quando si tratta di creare oggetti <strong>esperienze di e-commerce eccezionali<\/strong> con Shopware, alcuni marchi leader stanno indicando la strada. <strong>Collezione Amen<\/strong>, rinomata casa di moda italiana, <strong>AlexMax<\/strong>, un fornitore di soluzioni IT all&#8217;avanguardia, e <strong>Agenzia WODKA<\/strong>, una potente agenzia digitale, hanno tutti sfruttato le capacit\u00e0 headless di Shopware per ottenere risultati straordinari.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.bhoost.com\/\"><strong>Bhoost<\/strong><\/a> \u00e8 orgoglioso di far parte dei loro viaggi. Abbiamo fornito a questi marchi <strong>Hosting di Shopware ad alte prestazioni<\/strong> soluzioni, garantendo <strong>prestazioni senza soluzione di continuit\u00e0<\/strong> E <strong>affidabilit\u00e0 incrollabile<\/strong> per i loro negozi online.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.amencollection.com\/it-it\"><strong>Collezione Amen<\/strong><\/a><strong>:<\/strong> Immagina di navigare <strong>squisiti design della moda italiana<\/strong> su una piattaforma che \u00e8 <strong>liscia come la seta<\/strong>. Questa \u00e8 l&#8217;esperienza della Amen Collection, fornita da Shopware e <strong>supportato dall&#8217;esperienza di hosting di Bhoost<\/strong>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXcfiL15Nf91n3JFO3gL2HyFF7jdsLCioKFwwxxs1gS_0PwAOuKauZrKi-KoZLfjfSxFB9XWHv-yelxrg2GUjXj8y-i7kUxHE3CsTQSnTe2UF5Lp3EyuwkRFMjazJNQkCSfXj6N0Dz-pKlhosOUXIuKRvks?key=0EFeRUHh5aaofF9jTLfgAw\" alt=\"Shopware-hosting_headless-commerce_bhoost\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.alexmax.net\/en\/\"><strong>AlexMax<\/strong><\/a><strong>:<\/strong> Per un&#8217;azienda che opera nel <strong>soluzioni IT mission-critical<\/strong>, l&#8217;affidabilit\u00e0 \u00e8 fondamentale. <strong>Hosting Shopware di Bhoost<\/strong> garantisce che la piattaforma di e-commerce di AlexMax possa <strong>gestire elevati volumi di traffico<\/strong> con facilit\u00e0, fornendo a <strong>esperienza di acquisto senza attriti<\/strong> per i loro clienti.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXf93uzFpsTuV6UP7_1wbnKEdF1o0QxModhEtgomHY7pVzcf1xYT3LFmrSAeaBba13ND2zydRNCSmU6PB4_2M2GdIj5XuVdGqozi2enLkkRwGCgGeY2P_vdSCJHL0astrLPH9tpUR84YNtRko8OcPuq0YIjW?key=0EFeRUHh5aaofF9jTLfgAw\" alt=\"The power of headless commerce with Shopware\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.wodka.agency\/index.html\"><strong>Agenzia WODKA<\/strong><\/a><strong>:<\/strong> Questa agenzia innovativa <strong>collabora con i clienti per creare esperienze di e-commerce eccezionali<\/strong>e Shopware \u00e8 uno strumento di scelta. <strong>La competenza tecnica di Bhoost<\/strong> nell&#8217;hosting locale di Shopware <strong>sostiene l&#8217;Agenzia WODKA<\/strong> nella consegna <strong>soluzioni all&#8217;avanguardia<\/strong>.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdn2ZbK7FpKJPWelDWmQbD5IznS2lC2YLZduL6wvPRH2JhbqH7eFMugrhwnhV0QydBhkE0WqIxg-L4WB1B0V-LqIX0DOxalqM7sNRSwgdqnfThDdF1A_ERlGUs24aVN3HodT-s7yAs_VvJe5AvmHrTASBd8?key=0EFeRUHh5aaofF9jTLfgAw\" alt=\"Wodka_Shopware_Bhoost_headless-commerce\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.bhoost.com\/contact\/\"><strong>Bhoost<\/strong><\/a> \u00e8 entusiasta di aiutare le imprese a <strong>prosperare nel panorama dell\u2019e-commerce<\/strong>. Il nostro team di <strong>specialisti<\/strong> \u00e8 qui per <strong>guidarti in ogni fase del percorso<\/strong>.<\/p>\n\n\n\n<p>Questo \u00e8 tutto, gente! Dai un&#8217;occhiata al nostro <a href=\"https:\/\/www.bhoost.com\/iti\/blog\/\">blog<\/a> per maggiori informazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immagina di abbandonare i limiti di un negozio online tradizionale e di creare esperienze di acquisto uniche che catturino i [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-piattaforme-ecommerce"],"acf":[],"jetpack_featured_media_url":"https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png","uagb_featured_image_src":{"full":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",1200,628,false],"thumbnail":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",150,79,false],"medium":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",300,157,false],"medium_large":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",768,402,false],"large":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",768,402,false],"1536x1536":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",1200,628,false],"2048x2048":["https:\/\/www.bhoost.com\/it\/wp-content\/uploads\/sites\/2\/2024\/07\/thepower_shopaware_ita.png",1200,628,false]},"uagb_author_info":{"display_name":"manuelam","author_link":"https:\/\/www.bhoost.com\/it\/author\/manuelam\/"},"uagb_comment_info":0,"uagb_excerpt":"Immagina di abbandonare i limiti di un negozio online tradizionale e di creare esperienze di acquisto uniche che catturino i [&hellip;]","_links":{"self":[{"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/posts\/1897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/comments?post=1897"}],"version-history":[{"count":1,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/posts\/1897\/revisions"}],"predecessor-version":[{"id":1899,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/posts\/1897\/revisions\/1899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/media\/1898"}],"wp:attachment":[{"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/media?parent=1897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/categories?post=1897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bhoost.com\/it\/wp-json\/wp\/v2\/tags?post=1897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}